{"id":136087,"date":"2025-03-14T11:11:59","date_gmt":"2025-03-14T17:11:59","guid":{"rendered":"https:\/\/leadershipcircle.com\/?p=136087"},"modified":"2025-07-02T08:20:36","modified_gmt":"2025-07-02T14:20:36","slug":"as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente","status":"publish","type":"post","link":"https:\/\/leadershipcircle.com\/pt-br\/blog\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\/","title":{"rendered":"As 15 principais ferramentas de avalia\u00e7\u00e3o de coaching para impulsionar o sucesso do cliente"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Ir para as principais escolhas em cada categoria&#8221; font_container=&#8221;tag:h5|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][divider line_type=&#8221;No Line&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"icon-salient-thin-line\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"default\" data-alignment=\"left\"> \n<ul>\n<li><a href=\"#L\"><b>Avalia\u00e7\u00f5es de lideran\u00e7a<\/b><\/a><\/li>\n<li><a href=\"#P\"><b>Avalia\u00e7\u00f5es de personalidade<\/b><\/a><\/li>\n<li><a href=\"#E\"><b>Avalia\u00e7\u00f5es de intelig\u00eancia emocional<\/b><\/a><\/li>\n<li><a href=\"#V\"><b>Avalia\u00e7\u00f5es de valores<\/b><\/a><\/li>\n<li><a href=\"#MB\"><b>Avalia\u00e7\u00f5es de motiva\u00e7\u00e3o e comportamento<\/b><\/a><\/li>\n<\/ul>\n <\/div>[\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"icon-salient-thin-line\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"default\" data-alignment=\"left\"> \n<ul>\n<li><a href=\"#S\"><b>Avalia\u00e7\u00f5es de pontos fortes<\/b><\/a><\/li>\n<li><a href=\"#C\"><b>Avalia\u00e7\u00f5es de habilidades cognitivas<\/b><\/a><\/li>\n<li><a href=\"#I\"><b>Avalia\u00e7\u00f5es de interesses<\/b><\/a><\/li>\n<li><a href=\"https:\/\/leadershipcircle.com\/blog\/top-team-assessments\/\" target=\"_blank\" rel=\"noopener\"><strong>Avalia\u00e7\u00f5es de equipe<\/strong><\/a><\/li>\n<\/ul>\n <\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;O valor das ferramentas de avalia\u00e7\u00e3o no coaching&#8221; use_theme_fonts=&#8221;yes&#8221;][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<span style=\"font-weight: 400;\">As ferramentas de avalia\u00e7\u00e3o s\u00e3o parte essencial do coaching. Elas ajudam os coaches a compreender profundamente as necessidades, pontos fortes e \u00e1reas de melhoria dos clientes, permitindo a cria\u00e7\u00e3o de estrat\u00e9gias personalizadas que aceleram seu desenvolvimento. Al\u00e9m de fornecerem refer\u00eancias e acompanharem o progresso, essas ferramentas trazem mais estrutura \u00e0s sess\u00f5es de coaching, diminuindo a dist\u00e2ncia entre onde o cliente est\u00e1 e onde deseja chegar.<br \/>\nNo fim das contas, um processo de coaching bem estruturado gera melhores resultados e aumenta a satisfa\u00e7\u00e3o do cliente. No entanto, o desafio est\u00e1 em escolher ferramentas confi\u00e1veis e eficazes, que estejam alinhadas com sua pr\u00e1tica. Neste guia, abordaremos uma ampla variedade de ferramentas de avalia\u00e7\u00e3o de coaching, explorando suas aplica\u00e7\u00f5es, benef\u00edcios e as principais dimens\u00f5es que avaliam.<br \/>\nSeja para entender melhor seus clientes, acompanhar sua evolu\u00e7\u00e3o ou destacar seus servi\u00e7os em um mercado competitivo, escolher as ferramentas certas pode fazer toda a diferen\u00e7a.<\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Tipos e aplica\u00e7\u00f5es de ferramentas de avalia\u00e7\u00e3o de coaching&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<span style=\"font-weight: 400;\">Seja ao trabalhar habilidades de lideran\u00e7a no ambiente executivo ou intelig\u00eancia emocional no desenvolvimento pessoal, \u00e9 essencial considerar o prop\u00f3sito espec\u00edfico da ferramenta e sua relev\u00e2ncia para os objetivos do cliente.A seguir, veja os principais tipos de ferramentas de avalia\u00e7\u00e3o, com base no que medem, nossas recomenda\u00e7\u00f5es em cada categoria e como elas podem ser utilizadas no coaching.<\/span>[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][tabbed_section style=&#8221;minimal&#8221; tab_change_animation=&#8221;fade&#8221; alignment=&#8221;left&#8221; spacing=&#8221;default&#8221; tab_color=&#8221;Accent-Color&#8221; vs_content_animation=&#8221;fade&#8221; vs_link_animation=&#8221;opacity&#8221; vs_navigation_alignment=&#8221;left&#8221; vs_navigation_width_2=&#8221;25%&#8221; vs_navigation_func=&#8221;default&#8221; vs_navigation_width=&#8221;regular&#8221; vs_navigation_spacing=&#8221;15px&#8221; vs_navigation_mobile_display=&#8221;visible&#8221; vs_tab_spacing=&#8221;5%&#8221; cta_button_style=&#8221;accent-color&#8221; icon_size=&#8221;24&#8243;][tab icon_family=&#8221;none&#8221; title=&#8221;Lideran\u00e7a&#8221; id=&#8221;1734477249752-6&#8243; tab_id=&#8221;1734477249753-3&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<b><a href=\"#L\">Avalia\u00e7\u00f5es de Lideran\u00e7a<\/a> &#8211; <\/b>Avaliam os clientes com base em compet\u00eancias j\u00e1 reconhecidas como essenciais para uma lideran\u00e7a eficaz. Embora o coaching de lideran\u00e7a seja uma especialidade por si s\u00f3, esse tipo de avalia\u00e7\u00e3o \u00e9 amplamente aplic\u00e1vel e \u00fatil para diferentes perfis de clientes. Como as habilidades de lideran\u00e7a s\u00e3o cruciais para o crescimento pessoal e profissional, essas avalia\u00e7\u00f5es s\u00e3o indicadas em diversos contextos, como coaching de vida, carreira, executivo e de equipes.<\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#L1\">Avalia\u00e7\u00e3o 360<\/a> Leadership Circle Profile\u2122<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#L2\"><span style=\"font-weight: 400;\">Collective Leadership Assessment\u2122<\/span><\/a><\/li>\n<\/ul>\n[\/vc_column_text][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Personalidade&#8221; id=&#8221;1734477249763-7&#8243; tab_id=&#8221;1734477249763-8&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<b><a href=\"#P\">Avalia\u00e7\u00f5es de personalidade<\/a> &#8211; <\/b><span style=\"font-weight: 400;\">uxiliam na compreens\u00e3o dos padr\u00f5es caracter\u00edsticos de pensamentos, emo\u00e7\u00f5es e comportamentos de um indiv\u00edduo. Oferecem um entendimento profundo de como os tra\u00e7os pessoais afetam as intera\u00e7\u00f5es e comportamentos. Esses insights ajudam os coaches a adaptar suas estrat\u00e9gias de coaching para aproveitar os pontos fortes e prefer\u00eancias do cliente, al\u00e9m de identificar ambientes onde o cliente pode prosperar e alcan\u00e7ar realiza\u00e7\u00e3o.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#P1\"><span style=\"font-weight: 400;\">Invent\u00e1rio de Personalidade Hogan<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#P2\"><span style=\"font-weight: 400;\">Avalia\u00e7\u00e3o DISC<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#P3\"><span style=\"font-weight: 400;\">Question\u00e1rio Ocupacional de Personalidade Eneagrama (OPQ)<\/span><\/a><\/li>\n<\/ul>\n<p>&nbsp;[\/vc_column_text][\/tab][tab icon_family=&#8221;none&#8221; tab_id=&#8221;1734477249772-0&#8243; title=&#8221;Intelig\u00eancia emocional&#8221; id=&#8221;1734477249772-3&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<b><a href=\"#E\">Avalia\u00e7\u00f5es de Intelig\u00eancia Emocional<\/a> &#8211; <\/b><span style=\"font-weight: 400;\">Avaliam a capacidade das pessoas de gerenciar suas pr\u00f3prias emo\u00e7\u00f5es e compreender as emo\u00e7\u00f5es dos outros. Os coaches podem usar essas ferramentas para entender melhor os pontos fortes e desafios emocionais dos clientes, criando interven\u00e7\u00f5es espec\u00edficas que ajudam a alcan\u00e7ar sucesso pessoal e profissional, resultando em um coaching mais eficaz e significativo.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#E1\"><span style=\"font-weight: 400;\">Invent\u00e1rio de Quociente Emocional de BarOn (EQ-i)<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#E2\"><span style=\"font-weight: 400;\">Teste de intelig\u00eancia emocional Mayer-Salovey-Caruso (MSCEIT)<\/span><\/a><\/li>\n<\/ul>\n<p>&nbsp;[\/vc_column_text][\/tab][tab icon_family=&#8221;none&#8221; tab_id=&#8221;1734477249781-9&#8243; title=&#8221;Valores&#8221; id=&#8221;1734477249781-7&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<b><a href=\"#V\">Avalia\u00e7\u00f5es de Valores<\/a> &#8211; <\/b><span style=\"font-weight: 400;\">Ajudam a revelar o que as pessoas valorizam e priorizam, com base em seus valores fundamentais, que influenciam suas decis\u00f5es e motiva\u00e7\u00f5es. Ao ajudar os clientes a entender e expressar seus valores, os coaches podem auxili\u00e1-los a identificar e resolver conflitos de valores que podem estar causando estresse ou impedindo seu progresso. Esse entendimento tamb\u00e9m orienta a tomada de decis\u00f5es e o estabelecimento de metas alinhadas aos valores centrais do cliente. Essa abordagem pode aumentar n\u00e3o s\u00f3 o comprometimento, mas tamb\u00e9m a motiva\u00e7\u00e3o e a realiza\u00e7\u00e3o pessoal.\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#V1\"><span style=\"font-weight: 400;\">Question\u00e1rio de Valores Portrait (PVQ)<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#V2\"><span style=\"font-weight: 400;\">Avalia\u00e7\u00e3o de Valores Pessoais Barrett<\/span><\/a><\/li>\n<\/ul>\n<p>&nbsp;[\/vc_column_text][\/tab][tab icon_family=&#8221;none&#8221; tab_id=&#8221;1734477249790-7&#8243; title=&#8221;Motiva\u00e7\u00e3o\/Comportamento&#8221; id=&#8221;1734477249790-2&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<b><a href=\"#MB\">Avalia\u00e7\u00f5es de Motiva\u00e7\u00e3o e Comportamento<\/a> &#8211; <\/b><span style=\"font-weight: 400;\">Analisam as for\u00e7as que impulsionam as a\u00e7\u00f5es de uma pessoa. Ao identificar o que realmente motiva o cliente, os coaches podem adaptar suas abordagens para estar alinhados com essa compreens\u00e3o. Essa personaliza\u00e7\u00e3o torna as sess\u00f5es de coaching mais relevantes e eficazes, gerando resultados mais impactantes.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#MB1\"><span style=\"font-weight: 400;\">The Predictive Index<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#MB2\"><span style=\"font-weight: 400;\">Reiss Motivation Profile<\/span><\/a><\/li>\n<\/ul>\n[\/vc_column_text][\/tab][tab icon_family=&#8221;none&#8221; tab_id=&#8221;1734477249797-6&#8243; title=&#8221;Pontos fortes&#8221; id=&#8221;1734477249797-4&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<b><a href=\"#S\">Avalia\u00e7\u00f5es de Pontos Fortes<\/a> &#8211; <\/b><span style=\"font-weight: 400;\">Ajudam a identificar os principais talentos de uma pessoa, que podem ser usados para alcan\u00e7ar sucesso e realiza\u00e7\u00e3o em diferentes \u00e1reas da vida. Os coaches podem utilizar esses resultados para ajudar os clientes a potencializar seus pontos fortes, gerenciar suas limita\u00e7\u00f5es, aumentar a confian\u00e7a e acelerar o progresso rumo aos seus objetivos.\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#S1\"><span style=\"font-weight: 400;\">CliftonStrengths<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#S2\"><span style=\"font-weight: 400;\">Teste de For\u00e7as de Car\u00e1ter VIA<\/span><\/a><\/li>\n<\/ul>\n[\/vc_column_text][\/tab][tab icon_family=&#8221;none&#8221; tab_id=&#8221;1734477249804-5&#8243; title=&#8221;Capacidade cognitiva&#8221; id=&#8221;1734477249803-1&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<b><a href=\"#C\">Avalia\u00e7\u00f5es de Capacidade Cognitiva<\/a> &#8211; <\/b><span style=\"font-weight: 400;\">Abrangem uma variedade de processos e habilidades mentais, como mem\u00f3ria, racioc\u00ednio, resolu\u00e7\u00e3o de problemas e compreens\u00e3o. Os coaches podem usar essas informa\u00e7\u00f5es para criar planos de desenvolvimento focados em aprimorar as habilidades anal\u00edticas dos clientes, preparando-os para desafios profissionais complexos e apoiando seu crescimento pessoal e avan\u00e7o na carreira. Ao reconhecer e validar as capacidades cognitivas dos clientes, os coaches podem orient\u00e1-los rumo a oportunidades alinhadas com suas habilidades naturais e potencial de crescimento.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#C1\"><span style=\"font-weight: 400;\">Watson-Glaser<\/span><\/a><\/li>\n<\/ul>\n[\/vc_column_text][\/tab][tab icon_family=&#8221;none&#8221; tab_id=&#8221;1734477249813-8&#8243; title=&#8221;Interesses&#8221; id=&#8221;1734477249813-10&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<b><a href=\"#I\"><strong data-start=\"60\" data-end=\"88\">Avalia\u00e7\u00f5es de Interesses<\/strong><\/a> &#8211; <\/b><span style=\"font-weight: 400;\">Identificam paix\u00f5es e prefer\u00eancias, ajudando a orientar decis\u00f5es de vida, como as profiss\u00f5es que a pessoa provavelmente ir\u00e1 gostar. Os coaches podem usar esses insights para ajudar os clientes a descobrir carreiras alinhadas aos seus interesses, resultando em maior satisfa\u00e7\u00e3o e realiza\u00e7\u00e3o profissional.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#I1\"><span style=\"font-weight: 400;\">Strong Interest Inventory<\/span><\/a><\/li>\n<\/ul>\n[\/vc_column_text][\/tab][tab icon_family=&#8221;none&#8221; tab_id=&#8221;1734477249813-8&#8243; title=&#8221;Avalia\u00e7\u00f5es de equipe&#8221; id=&#8221;1734477249813-10&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<a href=\"https:\/\/leadershipcircle.com\/blog\/top-team-assessments\/\" target=\"_blank\" rel=\"noopener\"><b>Avalia\u00e7\u00f5es de Equipes<\/b><\/a><span style=\"font-weight: 400;\"> &#8211; Diferentemente das avalia\u00e7\u00f5es individuais, as avalia\u00e7\u00f5es de equipes s\u00e3o projetadas para analisar o funcionamento coletivo do grupo, oferecendo insights sobre como a equipe se relaciona e atua como uma unidade coesa, ao medir fatores que impulsionam ou dificultam o sucesso do time. Essas informa\u00e7\u00f5es valiosas orientam iniciativas de desenvolvimento da equipe, ajudando os coaches a criar estrat\u00e9gias espec\u00edficas para melhorar o desempenho geral. Para saber mais, confira nosso post abaixo, dedicado a este tema. <\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/leadershipcircle.com\/blog\/top-team-assessments\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Principais Avalia\u00e7\u00f5es de Equipes para Alta Performance<\/span><\/a><\/li>\n<\/ul>\n[\/vc_column_text][\/tab][\/tabbed_section][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Escolhendo a avalia\u00e7\u00e3o &quot;certa&quot; para seus clientes&#8221; use_theme_fonts=&#8221;yes&#8221;][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<span style=\"font-weight: 400;\">Selecionar as ferramentas de avalia\u00e7\u00e3o de coaching mais adequadas \u00e0 sua pr\u00e1tica \u00e9 uma decis\u00e3o estrat\u00e9gica, baseada nas necessidades espec\u00edficas dos seus clientes e nas compet\u00eancias que deseja desenvolver. Ao decidir quais ferramentas de avalia\u00e7\u00e3o utilizar, os coaches devem come\u00e7ar com uma compreens\u00e3o b\u00e1sica do que gostariam de medir, guiados pelos objetivos de seus clientes.\u00a0<\/span><\/p>\n<p>Al\u00e9m disso, \u00e9 importante considerar o prop\u00f3sito espec\u00edfico das ferramentas e como elas podem ser adaptadas a diferentes tipos de interven\u00e7\u00f5es de coaching. Por exemplo, uma avalia\u00e7\u00e3o de lideran\u00e7a pode encontrar aplica\u00e7\u00e3o em v\u00e1rios contextos, como coaching executivo, coaching de vida ou coaching de carreira, dependendo das necessidades do cliente. Como coach, o seu papel \u00e9 identificar as habilidades e atributos essenciais que moldam os perfis de sucesso dos seus clientes e selecionar ferramentas de avalia\u00e7\u00e3o que sejam especificamente projetadas para avaliar essas qualidades, fazendo uma ponte eficaz entre as metas deles e as suas estrat\u00e9gias de coaching.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Avalia\u00e7\u00e3o da confiabilidade e da validade da avalia\u00e7\u00e3o&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<span style=\"font-weight: 400;\">No campo din\u00e2mico do coaching, as ferramentas e os m\u00e9todos que escolhemos podem impactar significativamente os resultados de nossos compromissos de coaching. Portanto, ao selecionar ferramentas para a sua pr\u00e1tica, \u00e9 imperativo distinguir entre as ferramentas de avalia\u00e7\u00e3o que s\u00e3o baseadas em evid\u00eancias e aquelas que n\u00e3o s\u00e3o. As ferramentas de avalia\u00e7\u00e3o s\u00e3o frequentemente avaliadas em termos de sua confiabilidade e validade cient\u00edficas. Enquanto a validade considera a efic\u00e1cia de uma avalia\u00e7\u00e3o em medir o que ela foi projetada para medir, a confiabilidade avalia a capacidade de uma avalia\u00e7\u00e3o de produzir resultados precisos e consistentes ao longo do tempo em uma variedade de cen\u00e1rios.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Muitas ferramentas de avalia\u00e7\u00e3o de coaching n\u00e3o t\u00eam o respaldo cient\u00edfico necess\u00e1rio para fazer essas afirma\u00e7\u00f5es, sendo capazes de fornecer apenas percep\u00e7\u00f5es inferidas de n\u00edvel superficial. Essas ferramentas geralmente n\u00e3o passam pelo mesmo n\u00edvel de escrut\u00ednio que as ferramentas baseadas em evid\u00eancias com rela\u00e7\u00e3o \u00e0 sua confiabilidade e validade, o que as torna menos confi\u00e1veis. Dessa forma, confiar em tais ferramentas pode resultar em estrat\u00e9gias equivocadas que n\u00e3o atendem com precis\u00e3o \u00e0s necessidades ou ao potencial do cliente.\u00a0<\/span><\/p>\n<p>Embora todas as ferramentas de avalia\u00e7\u00e3o de coaching apresentadas neste guia sejam altamente consideradas e amplamente utilizadas na comunidade de coaching, \u00e9 importante observar que apenas algumas ferramentas de avalia\u00e7\u00e3o atendem aos crit\u00e9rios para serem consideradas baseadas em evid\u00eancias em termos de validade e confiabilidade. Se dispon\u00edveis, essas informa\u00e7\u00f5es ser\u00e3o listadas para cada avalia\u00e7\u00e3o apresentada.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Formatos administrativos comuns&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<span style=\"font-weight: 400;\">H\u00e1 dois formatos administrativos principais quando se trata de avalia\u00e7\u00f5es de coaching, cada um com suas vantagens exclusivas:\u00a0<\/span><\/p>\n<p><b>Autoavalia\u00e7\u00f5es: <\/b><span style=\"font-weight: 400;\">\u00a0permitem que os indiv\u00edduos avaliem a si mesmos, concentrando-se em suas percep\u00e7\u00f5es de suas pr\u00f3prias habilidades, comportamentos e impactos. Essas avalia\u00e7\u00f5es estimulam a introspec\u00e7\u00e3o e a autorreflex\u00e3o, o que as torna valiosas para o crescimento pessoal e a autoconsci\u00eancia.<\/span><\/p>\n<p><b>Avalia\u00e7\u00f5es 360: <\/b><span style=\"font-weight: 400;\">tamb\u00e9m chamadas de feedback de m\u00faltiplos avaliadores, consistem na coleta de percep\u00e7\u00f5es e opini\u00f5es sobre o cliente a partir de um grupo diversificado de pessoas com quem ele interage em seu ambiente profissional. Esse grupo geralmente inclui n\u00e3o apenas o pr\u00f3prio cliente, mas tamb\u00e9m gestores, colegas e subordinados. O principal benef\u00edcio das avalia\u00e7\u00f5es 360 \u00e9 oferecer uma vis\u00e3o ampla e completa das habilidades, comportamentos e impacto do indiv\u00edduo \u2014 revelando aspectos que dificilmente seriam percebidos a partir de uma \u00fanica perspectiva.<\/span>[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Principais ferramentas de avalia\u00e7\u00e3o de coaching&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<span style=\"font-weight: 400;\">As avalia\u00e7\u00f5es a seguir foram selecionadas como as melhores op\u00e7\u00f5es para aplica\u00e7\u00f5es de coaching devido ao seu uso generalizado, alta reputa\u00e7\u00e3o e versatilidade. Muitos desses instrumentos, embora n\u00e3o todos, s\u00e3o baseados em pesquisas cient\u00edficas rigorosas, passam por testes extensivos e s\u00e3o apoiados por dados emp\u00edricos para garantir sua confiabilidade e\/ou validade.<\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;L&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221;][divider line_type=&#8221;No Line&#8221;][vc_custom_heading text=&#8221;Avalia\u00e7\u00f5es de lideran\u00e7a&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;L1&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; boxed=&#8221;true&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;44201&#8243; image_size=&#8221;thumbnail&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><a href=\"https:\/\/leadershipcircle.com\/pt-br\/ferramentas-de-avaliacao-da-lideranca\/leadership-circle-profile\/\">Avalia\u00e7\u00e3o 360 Leadership Circle Profile\u2122<\/a><\/span><\/h5>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Descri\u00e7\u00e3o: <\/strong><span style=\"font-weight: 400;\">O Leadership Circle Profile\u2122 mede as cren\u00e7as e suposi\u00e7\u00f5es subjacentes que orientam nosso comportamento de lideran\u00e7a. \u00c9 o \u00fanico instrumento que avalia tanto as Compet\u00eancias Criativas que tornam os l\u00edderes eficazes quanto as Tend\u00eancias Reativas que prejudicam o sucesso dos l\u00edderes. Como uma Avalia\u00e7\u00e3o 360, o LCP se baseia em feedback pessoal e de v\u00e1rios avaliadores para oferecer uma vis\u00e3o realmente abrangente da efic\u00e1cia da lideran\u00e7a de seu cliente. Os resultados s\u00e3o sintetizados em tempo real, revelando instantaneamente as percep\u00e7\u00f5es mais impactantes.\u00a0<\/span><\/p>\n<p><strong>Aplica\u00e7\u00f5es de Coaching:<b>\u00a0<\/b><span style=\"font-weight: 400;\">Ao avaliar os clientes com base em uma bateria de compet\u00eancias bem pesquisadas que compreendem a efic\u00e1cia da lideran\u00e7a, os coaches podem criar estrat\u00e9gias de coaching altamente informadas e eficazes que fortale\u00e7am a capacidade de lideran\u00e7a, melhorem o desempenho, apoiem o avan\u00e7o na carreira e influenciem o sucesso organizacional.<\/span>\u00a0<\/strong><\/p>\n<p><strong>Formato: <\/strong>Avalia\u00e7\u00e3o 360\u00b0<\/p>\n<p><strong>Requisitos especiais: <span style=\"font-weight: 400;\">Certifica\u00e7\u00e3o necess\u00e1ria para administrar e interpretar<\/span><\/strong><\/p>\n<p><strong>Base de evid\u00eancias: <\/strong><span style=\"font-weight: 400;\">Confirmado pelo Institute for Psychological Research and Application (IPRA) como uma &#8220;medida v\u00e1lida e internamente consistente para o desenvolvimento de lideran\u00e7a&#8221;.<\/span><b>\u201d <\/b><span style=\"font-weight: 400;\">Consulte o <\/span><a href=\"https:\/\/leadershipcircle.com\/wp-content\/uploads\/2018\/03\/IPRA-Technical-Report_Psychometric-Evaluation-of-TLCP.pdf\">Estudo de valida\u00e7\u00e3o do instrumento<\/a><\/p>\n<p><strong>Recursos adicionais:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/leadershipcircle.com\/whitepapers\/\">Documento t\u00e9cnicos<\/a><\/li>\n<li><a href=\"https:\/\/leadershipcircle.com\/case-studies\/\">Estudos de casos<\/a><\/li>\n<\/ul>\n<p><strong>Pre\u00e7os: <span style=\"font-weight: 400;\">Entre em contato com o fornecedor para obter detalhes. <\/span><\/strong><span style=\"font-weight: 400;\"><a href=\"https:\/\/leadershipcircle.com\/pt-br\/autoavaliacao-gratuita\/\">Autoavalia\u00e7\u00e3o gratuita<\/a><\/span><strong><span style=\"font-weight: 400;\"> limitada e dispon\u00edvel.<\/span><\/strong>[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221;][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; text=&#8221;Saiba mais&#8221; url=&#8221;https:\/\/leadershipcircle.com\/pt-br\/ferramentas-de-avaliacao-da-lideranca\/leadership-circle-profile\/&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;L2&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; boxed=&#8221;true&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;128732&#8243; image_size=&#8221;thumbnail&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p><\/p>\n<h5 style=\"text-align: center;\"><a href=\"https:\/\/leadershipcircle.com\/pt-br\/ferramentas-de-avaliacao-da-lideranca\/collective-leadership-assessment\/\"><u>Collective Leadership Assessment\u2122<\/u><\/a><\/h5>\n<p><\/p>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Descri\u00e7\u00e3o: <span style=\"font-weight: 400;\">Semelhante ao Leadership Circle Profile\u2122 mencionado acima, o CLA foi desenvolvido com base no mesmo modelo propriet\u00e1rio, mas mede a efic\u00e1cia da lideran\u00e7a em um n\u00edvel coletivo e fornece uma lente poderosa sobre a din\u00e2mica em jogo dentro de grupos e equipes. Essa avalia\u00e7\u00e3o re\u00fane as percep\u00e7\u00f5es de todos os membros para avaliar a efic\u00e1cia da lideran\u00e7a de grupos, desde os n\u00edveis de departamento at\u00e9 organiza\u00e7\u00f5es inteiras.<\/span><\/strong><\/p>\n<p><strong>Aplica\u00e7\u00f5es de coaching: <b> <span style=\"font-weight: 400;\">Ao compreender o impacto da lideran\u00e7a coletiva de grupos e equipes, os coaches podem identificar oportunidades de desenvolvimento direcionadas que influenciam diretamente a din\u00e2mica do grupo. Essa abordagem focada aumenta a coes\u00e3o e a produtividade da equipe, o que, em \u00faltima an\u00e1lise, leva \u00e0 melhoria e ao sucesso da organiza\u00e7\u00e3o.<\/span><\/b><\/strong><\/p>\n<p><strong>Formato: <\/strong>Avalia\u00e7\u00e3o 360\u00b0<\/p>\n<p><strong>Requisitos especiais: <span style=\"font-weight: 400;\">Certifica\u00e7\u00e3o necess\u00e1ria para administrar e interpretar<\/span><\/strong><\/p>\n<p><strong>Base de evid\u00eancias: <\/strong><span style=\"font-weight: 400;\">Baseado no mesmo modelo propriet\u00e1rio do Leadership Circle Profile, que foi considerado internamente consistente e uma medida v\u00e1lida para o desenvolvimento da lideran\u00e7a.Veja o <\/span><a href=\"https:\/\/leadershipcircle.com\/wp-content\/uploads\/2018\/03\/IPRA-Technical-Report_Psychometric-Evaluation-of-TLCP.pdf\"><span style=\"font-weight: 400;\">Instrument Validation Study (Estudo de valida\u00e7\u00e3o do instrumento)<\/span><\/a><\/p>\n<p><strong>Pre\u00e7os: <span style=\"font-weight: 400;\">Entre em contato com o fornecedor para obter detalhes<\/span><\/strong>[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221;][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; text=&#8221;Saiba mais&#8221; url=&#8221;https:\/\/leadershipcircle.com\/pt-br\/ferramentas-de-avaliacao-da-lideranca\/collective-leadership-assessment\/&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;P&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221;][divider line_type=&#8221;No Line&#8221;][vc_custom_heading text=&#8221;Avalia\u00e7\u00f5es de personalidade&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;P1&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; boxed=&#8221;true&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.hoganassessments.com\/assessment\/hogan-personality-inventory\/\" target=\"_blank\" rel=\"noopener\">Invent\u00e1rio de Personalidade Hogan<\/a><\/span><\/h5>\n<p>&nbsp;[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Descri\u00e7\u00e3o: <span style=\"font-weight: 400;\">Avalia o tipo de personalidade com base no Modelo de Cinco Fatores da personalidade. Essa avalia\u00e7\u00e3o de personalidade captura as principais tend\u00eancias comportamentais e ajuda os indiv\u00edduos a entender como se relacionam com os outros.<\/span><\/strong><\/p>\n<p><strong>Formato: <span style=\"font-weight: 400;\">Autoavalia\u00e7\u00e3o<\/span><\/strong><\/p>\n<p><strong>Requisitos especiais: <span style=\"font-weight: 400;\">Certifica\u00e7\u00e3o necess\u00e1ria para administrar e interpretar<\/span><\/strong><\/p>\n<p><strong>Base de evid\u00eancias: <span style=\"font-weight: 400;\">Consulte <a href=\"https:\/\/www.hoganassessments.com\/sites\/default\/files\/uploads\/Competency_Scoring_WP.pdf\" target=\"_blank\" rel=\"noopener\">Alinhamento das escalas Hogan com as compet\u00eancias<\/a><\/span><\/strong><\/p>\n<p><strong>Pre\u00e7os: <span style=\"font-weight: 400;\">Entre em contato com o fornecedor para obter detalhes<\/span><\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;P2&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; boxed=&#8221;true&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\"><a href=\"https:\/\/www.discprofile.com\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Avalia\u00e7\u00e3o DISC<\/span><\/a><\/h5>\n<p>&nbsp;[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Descri\u00e7\u00e3o: <span style=\"font-weight: 400;\">Avalia quatro perfis principais de personalidade: Domin\u00e2ncia, Influ\u00eancia, Estabilidade e Conscienciosidade. Ajuda as pessoas a entenderem seus estilos de comportamento e comunica\u00e7\u00e3o.<\/span><\/strong><\/p>\n<p><strong>Formato: <span style=\"font-weight: 400;\">Autoavalia\u00e7\u00e3o<\/span><\/strong><\/p>\n<p><strong>Requisitos especiais: <span style=\"font-weight: 400;\">Nenhum, embora a certifica\u00e7\u00e3o seja recomendada para aprimorar as habilidades de interpreta\u00e7\u00e3o<\/span><\/strong><\/p>\n<p><strong>Base de evid\u00eancias: <span style=\"font-weight: 400;\">Veja <\/span><a href=\"https:\/\/www.discprofile.com\/what-is-disc\/research-reliability-and-validity\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">A ci\u00eancia por tr\u00e1s do DISC\u00ae<\/span><\/a><\/strong><\/p>\n<p><strong>Pre\u00e7os: <span style=\"font-weight: 400;\">Entre em contato com o fornecedor para obter detalhes<\/span><\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;P3&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; boxed=&#8221;true&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><a href=\"https:\/\/enneagramtest.com\/\" target=\"_blank\" rel=\"noopener\">Question\u00e1rio de Personalidade Ocupacional do Eneagrama (OPQ)<\/a><\/span><\/h5>\n<p>&nbsp;[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Descri\u00e7\u00e3o: <span style=\"font-weight: 400;\">Fornece insights sobre a perspectiva emocional e os padr\u00f5es de comportamento de uma pessoa em nove tipos de personalidade. Ajuda as pessoas a se entenderem melhor em termos de seus padr\u00f5es emocionais, mentais e comportamentais.<\/span><\/strong><\/p>\n<p><strong>Formato: <span style=\"font-weight: 400;\">Autoavalia\u00e7\u00e3o<\/span><\/strong><\/p>\n<p><strong>Requisitos especiais: <span style=\"font-weight: 400;\">Nenhum<\/span><\/strong><\/p>\n<p><strong>Base de evid\u00eancias: <span style=\"font-weight: 400;\">N\u00e3o dispon\u00edvel<\/span><\/strong><\/p>\n<p><strong>Pre\u00e7os: <span style=\"font-weight: 400;\">Gratuito para a vers\u00e3o b\u00e1sica, embora seja necess\u00e1rio um upgrade pago para acessar o &#8220;relat\u00f3rio completo&#8221;.<\/span><\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;E&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221;][divider line_type=&#8221;No Line&#8221;][vc_custom_heading text=&#8221;Avalia\u00e7\u00f5es de intelig\u00eancia emocional&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;E1&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; boxed=&#8221;true&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><a href=\"https:\/\/storefront.mhs.com\/collections\/eq-i-2-0\" target=\"_blank\" rel=\"noopener\">Invent\u00e1rio de Quociente Emocional de BarOn (EQ-i)<\/a><\/span><\/h5>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Descri\u00e7\u00e3o: <span style=\"font-weight: 400;\">Avalia cinco aspectos distintos do funcionamento emocional e social, que incluem gerenciamento do estresse, autopercep\u00e7\u00e3o, autoexpress\u00e3o, tomada de decis\u00f5es e relacionamentos interpessoais.<\/span><\/strong><\/p>\n<p><strong>Formato: <span style=\"font-weight: 400;\">Autoavalia\u00e7\u00e3o<\/span><\/strong><\/p>\n<p><strong>Requisitos especiais: <span style=\"font-weight: 400;\">Certifica\u00e7\u00e3o necess\u00e1ria para administrar e interpretar<\/span><\/strong><\/p>\n<p><strong>Base de evid\u00eancias: <\/strong>Ver <a href=\"https:\/\/storefront.mhs.com\/collections\/eq-i-2-0\" target=\"_blank\" rel=\"noopener\">dados de confiabilidade e validade.<\/a><\/p>\n<p><strong>Pre\u00e7os: <span style=\"font-weight: 400;\">Entre em contato com o fornecedor para obter detalhes sobre pre\u00e7os<\/span><\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;E2&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; boxed=&#8221;true&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\"><a href=\"https:\/\/storefront.mhs.com\/collections\/msceit\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Teste de intelig\u00eancia emocional Mayer-Salovey-Caruso (MSCEIT)<\/span><\/a><\/h5>\n<p>&nbsp;[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Descri\u00e7\u00e3o: <span style=\"font-weight: 400;\">Mede a capacidade de perceber, usar, compreender e gerenciar emo\u00e7\u00f5es por meio de uma abordagem baseada no desempenho, testando diretamente a capacidade de uma pessoa de perceber, usar, compreender e gerenciar emo\u00e7\u00f5es.<\/span><\/strong><\/p>\n<p><strong>Formato: <span style=\"font-weight: 400;\">Autoavalia\u00e7\u00e3o<\/span><\/strong><\/p>\n<p><strong>Requisitos especiais: <span style=\"font-weight: 400;\">Certifica\u00e7\u00e3o necess\u00e1ria para administrar e interpretar<\/span><\/strong><\/p>\n<p><strong>Base de evid\u00eancias: <span style=\"font-weight: 400;\">N\u00e3o dispon\u00edvel<\/span><\/strong><\/p>\n<p><strong>Pre\u00e7os: <span style=\"font-weight: 400;\">Entre em contato com o fornecedor para obter detalhes<\/span><\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;V&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221;][divider line_type=&#8221;No Line&#8221;][vc_custom_heading text=&#8221;Avalia\u00e7\u00f5es de valores&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;V1&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; boxed=&#8221;true&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\"><a href=\"https:\/\/aidaform.com\/templates\/pvq-test.html\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Question\u00e1rio de Valores Portrait (PVQ)<\/span><\/a><\/h5>\n<p>&nbsp;[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Descri\u00e7\u00e3o: <span style=\"font-weight: 400;\">Mede os valores individuais com base na teoria dos valores humanos b\u00e1sicos de Schwartz, avaliando dez tipos diferentes de valores. Usado para selecionar valores essenciais em contextos pessoais e profissionais.<\/span><\/strong><\/p>\n<p><strong>Formato: <span style=\"font-weight: 400;\">Autoavalia\u00e7\u00e3o<\/span><\/strong><\/p>\n<p><strong>Requisitos especiais: <\/strong>Nenhum<\/p>\n<p><strong>Base de evid\u00eancias: <span style=\"font-weight: 400;\">Consulte <\/span><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/33682477\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">a psicometria do Portrait Value Questionnaire revisado<\/span><\/a><\/strong><\/p>\n<p><strong>Pre\u00e7os: <span style=\"font-weight: 400;\">Gratuito<\/span><\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;V2&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; boxed=&#8221;true&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\"><a href=\"https:\/\/www.valuescentre.com\/pva\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Avalia\u00e7\u00e3o de valores pessoais Barrett<\/span><\/a><\/h5>\n<p>&nbsp;[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Descri\u00e7\u00e3o: <span style=\"font-weight: 400;\">Avaliar os valores pessoais de acordo com sete \u00e1reas de foco bem definidas, criando consci\u00eancia de como os valores se relacionam com a motiva\u00e7\u00e3o e a tomada de decis\u00f5es.<\/span><\/strong><\/p>\n<p><strong>Formato: <span style=\"font-weight: 400;\">Autoavalia\u00e7\u00e3o<\/span><\/strong><\/p>\n<p><strong>Requisitos especiais: <\/strong>Nenhum<\/p>\n<p><strong>Base de evid\u00eancias: <span style=\"font-weight: 400;\">Veja o <a href=\"https:\/\/www.valuescentre.com\/articles\/theoretical-support-for-the-barrett-model\" target=\"_blank\" rel=\"noopener\">Suporte Te\u00f3rico para o Modelo Barret\u2122<\/a><\/span><\/strong><\/p>\n<p><strong>Pre\u00e7o: <span style=\"font-weight: 400;\">$19.95<\/span><\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;MB&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221;][divider line_type=&#8221;No Line&#8221;][vc_custom_heading text=&#8221;Avalia\u00e7\u00f5es de motiva\u00e7\u00e3o e comportamento&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;MB1&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; boxed=&#8221;true&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\"><a href=\"https:\/\/www.predictiveindex.com\/assessments\/behavioral-assessment\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Avalia\u00e7\u00e3o do comportamento do Predictive Index<\/span><\/a><\/h5>\n<p>&nbsp;[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Descri\u00e7\u00e3o: <span style=\"font-weight: 400;\">Essa ferramenta identifica os quatro principais impulsos comportamentais (Domin\u00e2ncia, Extrovers\u00e3o, Paci\u00eancia e Formalidade), fornecendo uma estrutura para entender como as motiva\u00e7\u00f5es se manifestam nos comportamentos no local de trabalho. Os coaches podem usar esses insights para orientar os clientes na escolha de caminhos de carreira que se alinhem com seus perfis comportamentais.<\/span><\/strong><\/p>\n<p><strong>Formato: <span style=\"font-weight: 400;\">Autoavalia\u00e7\u00e3o<\/span><\/strong><\/p>\n<p><strong>Requisitos especiais: <\/strong>Nenhum<\/p>\n<p><strong>Base de evid\u00eancias: <span style=\"font-weight: 400;\">Veja <a href=\"https:\/\/www.predictiveindex.com\/learn\/support\/research-and-validity-at-pi\/\" target=\"_blank\" rel=\"noopener\">Pesquisa e validade do PI<\/a><\/span><\/strong><\/p>\n<p><strong>Pre\u00e7os: <span style=\"font-weight: 400;\">Gratuito<\/span><\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;MB2&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; boxed=&#8221;true&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\"><a href=\"https:\/\/www.reissmotivationprofile.com\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Reiss Motivation Profile <\/span><\/a><\/h5>\n<p>&nbsp;[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Descri\u00e7\u00e3o: <span style=\"font-weight: 400;\">Oferece insights sobre os principais motivadores do comportamento de um indiv\u00edduo, examinando 16 motivos de vida distintos. Essa ferramenta ajuda a descobrir as motiva\u00e7\u00f5es fundamentais que influenciam as a\u00e7\u00f5es e decis\u00f5es.<\/span><\/strong><\/p>\n<p><strong>Formato: <span style=\"font-weight: 400;\">Autoavalia\u00e7\u00e3o<\/span><\/strong><\/p>\n<p><strong>Requisitos especiais: <span style=\"font-weight: 400;\">Certifica\u00e7\u00e3o necess\u00e1ria para administrar e interpretar<\/span><\/strong><\/p>\n<p><strong>Base de evid\u00eancias: <span style=\"font-weight: 400;\">Veja <\/span><a href=\"https:\/\/www.reissmotivationprofile.com\/research\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">os fundamentos cient\u00edficos do Reiss Motivation Profile\u00ae<\/span><\/a><\/strong><\/p>\n<p><strong>Pre\u00e7os: <span style=\"font-weight: 400;\">Entre em contato com o fornecedor para obter detalhes<\/span><\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;S&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221;][divider line_type=&#8221;No Line&#8221;][vc_custom_heading text=&#8221;Avalia\u00e7\u00f5es de pontos fortes&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;S1&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; boxed=&#8221;true&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\"><a href=\"https:\/\/www.gallup.com\/learning\/310085\/cliftonstrengths-discovery.aspx\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Pontos fortes da Clifton<\/span><\/a><\/h5>\n<p>&nbsp;[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Descri\u00e7\u00e3o: <span style=\"font-weight: 400;\">Mede os principais talentos e padr\u00f5es naturais de pensamento, sentimento e comportamento de um indiv\u00edduo.<\/span><\/strong><\/p>\n<p><strong>Formato: <span style=\"font-weight: 400;\">Autoavalia\u00e7\u00e3o<\/span><\/strong><\/p>\n<p><strong>Requisitos especiais: <span style=\"font-weight: 400;\">Nenhum, embora a certifica\u00e7\u00e3o seja recomendada para aprimorar as habilidades de interpreta\u00e7\u00e3o.<\/span><\/strong><\/p>\n<p><strong>Base de evid\u00eancias: <span style=\"font-weight: 400;\">Veja <\/span><a href=\"https:\/\/www.gallup.com\/cliftonstrengths\/en\/253790\/science-of-cliftonstrengths.aspx\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">a Ci\u00eancia da CliftonStrengths<\/span><\/a><\/strong><\/p>\n<p><strong>Pre\u00e7os: <span style=\"font-weight: 400;\">Entre em contato com o fornecedor para obter detalhes<\/span><\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;S2&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; boxed=&#8221;true&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\"><a href=\"https:\/\/www.viacharacter.org\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Teste de For\u00e7as de Car\u00e1ter VIA<\/span><\/a><\/h5>\n<p>&nbsp;[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Descri\u00e7\u00e3o: <span style=\"font-weight: 400;\">Mede 24 pontos fortes de car\u00e1ter que se enquadram em seis categorias amplas de virtudes, ajudando os indiv\u00edduos a entender suas caracter\u00edsticas principais.<\/span><\/strong><\/p>\n<p><strong>Formato: <span style=\"font-weight: 400;\">Autoavalia\u00e7\u00e3o<\/span><\/strong><\/p>\n<p><strong>Requisitos especiais: <span style=\"font-weight: 400;\">Nenhum<\/span><\/strong><\/p>\n<p><strong>Base de evid\u00eancias: <span style=\"font-weight: 400;\">Consulte <a href=\"https:\/\/www.viacharacter.org\/researchers\/assessments\/via-is\" target=\"_blank\" rel=\"noopener\">os dados de confiabilidade e validade publicados pelo VIA-IS<\/a><\/span><\/strong><\/p>\n<p><strong>Pre\u00e7os: <span style=\"font-weight: 400;\">Entre em contato com o provedor para obter detalhes. Vers\u00e3o gratuita limitada dispon\u00edvel.<\/span><\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;C&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221;][divider line_type=&#8221;No Line&#8221;][vc_custom_heading text=&#8221;Avalia\u00e7\u00f5es de habilidades cognitivas&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;C1&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; boxed=&#8221;true&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p><\/p>\n<h5 style=\"text-align: center;\"><a href=\"https:\/\/www.talentlens.com\/recruitment\/assessments\/watson-glaser-critical-thinking-appraisal.html\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Watson-Glaser<\/span><\/a><\/h5>\n<p><\/p>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Descri\u00e7\u00e3o: <span style=\"font-weight: 400;\">Avalia o pensamento cr\u00edtico e as habilidades de racioc\u00ednio e \u00e9 usado principalmente em um contexto profissional para o recrutamento de candidatos de alto potencial.<\/span><\/strong><\/p>\n<p><strong>Formato: <span style=\"font-weight: 400;\">Autoavalia\u00e7\u00e3o<\/span><\/strong><\/p>\n<p><strong>Requisitos especiais: <span style=\"font-weight: 400;\">Treinamento necess\u00e1rio para administrar e interpretar<\/span><\/strong><\/p>\n<p><strong>Base de evid\u00eancias: <span style=\"font-weight: 400;\">Consulte <\/span><a href=\"https:\/\/www.talentlens.com\/content\/dam\/school\/global\/Global-Talentlens\/uk\/Assessments\/WGCTA\/Watson-Glaser-Validity-Evidence-white-paper-global.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Evid\u00eancias de Validade do Watson-Glaser<\/span><\/a><\/strong><\/p>\n<p><strong>Pre\u00e7os: <span style=\"font-weight: 400;\">Entre em contato com o provedor para obter detalhes. <\/span><\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;I&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221;][divider line_type=&#8221;No Line&#8221;][vc_custom_heading text=&#8221;Avalia\u00e7\u00f5es de interesses&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;I1&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; boxed=&#8221;true&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h5 style=\"text-align: center;\"><a href=\"https:\/\/www.themyersbriggs.com\/en-US\/Products-and-Services\/Strong\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Invent\u00e1rio de Forte Interesse<\/span><\/a><\/h5>\n<p>&nbsp;[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Descri\u00e7\u00e3o: <span style=\"font-weight: 400;\">Uma ferramenta de explora\u00e7\u00e3o de carreira criada para ajudar as pessoas a identificar seus interesses e prefer\u00eancias de trabalho. Os resultados correlacionam os interesses de uma pessoa a poss\u00edveis carreiras que provavelmente levar\u00e3o \u00e0 satisfa\u00e7\u00e3o no trabalho.<\/span><\/strong><\/p>\n<p><strong>Formato: <span style=\"font-weight: 400;\">Autoavalia\u00e7\u00e3o<\/span><\/strong><\/p>\n<p><strong>Requisitos especiais: <span style=\"font-weight: 400;\">Certifica\u00e7\u00e3o necess\u00e1ria para administrar e interpretar<\/span><\/strong><\/p>\n<p><strong>Base de evid\u00eancias: <span style=\"font-weight: 400;\">Ver  <a href=\"https:\/\/www.themyersbriggs.com\/en-US\/Support\/Validity-of-the-Strong-Interest-Inventory\" target=\"_blank\" rel=\"noopener\">Validade do Strong Interest Inventory\u00ae (Invent\u00e1rio de Forte Interesse)<\/a><\/span><\/strong><\/p>\n<p><strong>Pre\u00e7os: <span style=\"font-weight: 400;\">Entre em contato com o provedor para obter detalhes. <\/span><\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Reconhecer os limites das ferramentas de avalia\u00e7\u00e3o&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<span style=\"font-weight: 400;\">Embora as avalia\u00e7\u00f5es de coaching possam agregar valor \u00e0 sua pr\u00e1tica, \u00e9 fundamental reconhecer suas limita\u00e7\u00f5es. Nenhuma ferramenta de avalia\u00e7\u00e3o \u00e9 capaz de capturar completamente a complexidade da psique humana. O uso excessivo dessas ferramentas pode levar alguns coaches a negligenciar aspectos qualitativos e sutis da intera\u00e7\u00e3o com o cliente, que s\u00e3o igualmente essenciais para um coaching eficaz. \u00c9 imprescind\u00edvel equilibrar os dados quantitativos fornecidos pelas avalia\u00e7\u00f5es com as percep\u00e7\u00f5es qualitativas adquiridas por meio do contato direto com o cliente. Assim, as ferramentas de avalia\u00e7\u00e3o devem ser integradas a uma abordagem mais ampla de coaching, que inclua intera\u00e7\u00f5es pessoais, observa\u00e7\u00f5es e outras formas de feedback. <\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Aplica\u00e7\u00e3o do feedback da avalia\u00e7\u00e3o para aprimorar as sess\u00f5es de coaching&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<span style=\"font-weight: 400;\">Ao aplicar o feedback da avalia\u00e7\u00e3o, \u00e9 fundamental destacar que, embora as avalia\u00e7\u00f5es forne\u00e7am percep\u00e7\u00f5es valiosas, sua efic\u00e1cia depende diretamente da habilidade do coach em interpretar e analisar esses resultados com precis\u00e3o. Alguns instrumentos exigem que os coaches sejam devidamente treinados para compreender e interpretar os dados corretamente. De fato, a arte da interpreta\u00e7\u00e3o \u00e9 t\u00e3o importante quanto a confiabilidade e a validade da avalia\u00e7\u00e3o em si. Um treinamento adequado no uso dessas ferramentas \u00e9 essencial, pois capacita os coaches a integrar os dados da avalia\u00e7\u00e3o de forma eficaz em um plano de desenvolvimento coerente, projetado para potencializar o crescimento do cliente.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando utilizadas corretamente, as ferramentas de avalia\u00e7\u00e3o de coaching oferecem percep\u00e7\u00f5es profundas e acion\u00e1veis que, de outra forma, levariam muito mais tempo para serem identificadas. Essas percep\u00e7\u00f5es auxiliam na cria\u00e7\u00e3o de estrat\u00e9gias de coaching mais embasadas, acelerando o processo de crescimento e desenvolvimento. A integra\u00e7\u00e3o das ferramentas de avalia\u00e7\u00e3o nas pr\u00e1ticas de coaching possui um potencial transformador. Por meio da sele\u00e7\u00e3o e aplica\u00e7\u00e3o criteriosa dessas ferramentas, os coaches podem aumentar significativamente sua efic\u00e1cia, acelerar resultados positivos e elevar a satisfa\u00e7\u00e3o geral dos clientes. <\/span>[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":54,"featured_media":119070,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[2084],"tags":[],"wf_post_folders":[],"class_list":["post-136087","post","type-post","status-publish","format-standard","has-post-thumbnail","category-coaches-pt-br"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>As 15 principais ferramentas de avalia\u00e7\u00e3o de coaching para impulsionar o sucesso do cliente - Leadership Circle\u00ae<\/title>\n<meta name=\"description\" content=\"Explore 15 das ferramentas de avalia\u00e7\u00e3o de coaching mais prestigiadas e eficazes para acelerar o crescimento dos clientes e ampliar o seu impacto como coach.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leadershipcircle.com\/pt-br\/blog\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As 15 principais ferramentas de avalia\u00e7\u00e3o de coaching para impulsionar o sucesso do cliente\" \/>\n<meta property=\"og:description\" content=\"Explore 15 das ferramentas de avalia\u00e7\u00e3o de coaching mais prestigiadas e eficazes para acelerar o crescimento dos clientes e ampliar o seu impacto como coach.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leadershipcircle.com\/pt-br\/blog\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\/\" \/>\n<meta property=\"og:site_name\" content=\"Leadership Circle\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheLeadershipCircle\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-14T17:11:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-02T14:20:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leadershipcircle.com\/wp-content\/uploads\/2024\/05\/Coaching-Assessment-Tools-4-e1716349407364-1024x592.jpg\" \/>\n<meta name=\"author\" content=\"Andrew Parker\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LeadershipCir\" \/>\n<meta name=\"twitter:site\" content=\"@LeadershipCir\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leadership Circle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/blog\\\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/blog\\\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\\\/\"},\"author\":{\"name\":\"Andrew Parker\",\"@id\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/bae433ccd0703f445e1fc51812ccbc0b\"},\"headline\":\"As 15 principais ferramentas de avalia\u00e7\u00e3o de coaching para impulsionar o sucesso do cliente\",\"datePublished\":\"2025-03-14T17:11:59+00:00\",\"dateModified\":\"2025-07-02T14:20:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/blog\\\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\\\/\"},\"wordCount\":10829,\"publisher\":{\"@id\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/blog\\\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leadershipcircle.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Coaching-Assessment-Tools-4-e1716349407364.jpg\",\"articleSection\":[\"Coaches\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/blog\\\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\\\/\",\"url\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/blog\\\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\\\/\",\"name\":\"As 15 principais ferramentas de avalia\u00e7\u00e3o de coaching para impulsionar o sucesso do cliente - Leadership Circle\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/blog\\\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/blog\\\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leadershipcircle.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Coaching-Assessment-Tools-4-e1716349407364.jpg\",\"datePublished\":\"2025-03-14T17:11:59+00:00\",\"dateModified\":\"2025-07-02T14:20:36+00:00\",\"description\":\"Explore 15 das ferramentas de avalia\u00e7\u00e3o de coaching mais prestigiadas e eficazes para acelerar o crescimento dos clientes e ampliar o seu impacto como coach.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/blog\\\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/blog\\\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/blog\\\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leadershipcircle.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Coaching-Assessment-Tools-4-e1716349407364.jpg\",\"contentUrl\":\"https:\\\/\\\/leadershipcircle.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Coaching-Assessment-Tools-4-e1716349407364.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/blog\\\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"As 15 principais ferramentas de avalia\u00e7\u00e3o de coaching para impulsionar o sucesso do cliente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/\",\"name\":\"Leadership Circle\",\"description\":\"The New Standard For Leadership Development\",\"publisher\":{\"@id\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/#organization\",\"name\":\"The Leadership Circle\",\"url\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/leadershipcircle.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Leadership-Circle-Logo-2021_sq-color.png\",\"contentUrl\":\"https:\\\/\\\/leadershipcircle.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Leadership-Circle-Logo-2021_sq-color.png\",\"width\":593,\"height\":593,\"caption\":\"The Leadership Circle\"},\"image\":{\"@id\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TheLeadershipCircle\\\/\",\"https:\\\/\\\/x.com\\\/LeadershipCir\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/the-leadership-circle\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leadershipcircle.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/bae433ccd0703f445e1fc51812ccbc0b\",\"name\":\"Andrew Parker\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/986943e43b09848d0c818b13ed40e33996f738b649d8a7c7126aeeb11be2ac6f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/986943e43b09848d0c818b13ed40e33996f738b649d8a7c7126aeeb11be2ac6f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/986943e43b09848d0c818b13ed40e33996f738b649d8a7c7126aeeb11be2ac6f?s=96&d=mm&r=g\",\"caption\":\"Andrew Parker\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As 15 principais ferramentas de avalia\u00e7\u00e3o de coaching para impulsionar o sucesso do cliente - Leadership Circle\u00ae","description":"Explore 15 das ferramentas de avalia\u00e7\u00e3o de coaching mais prestigiadas e eficazes para acelerar o crescimento dos clientes e ampliar o seu impacto como coach.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leadershipcircle.com\/pt-br\/blog\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\/","og_locale":"pt_BR","og_type":"article","og_title":"As 15 principais ferramentas de avalia\u00e7\u00e3o de coaching para impulsionar o sucesso do cliente","og_description":"Explore 15 das ferramentas de avalia\u00e7\u00e3o de coaching mais prestigiadas e eficazes para acelerar o crescimento dos clientes e ampliar o seu impacto como coach.","og_url":"https:\/\/leadershipcircle.com\/pt-br\/blog\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\/","og_site_name":"Leadership Circle\u00ae","article_publisher":"https:\/\/www.facebook.com\/TheLeadershipCircle\/","article_published_time":"2025-03-14T17:11:59+00:00","article_modified_time":"2025-07-02T14:20:36+00:00","og_image":[{"url":"https:\/\/leadershipcircle.com\/wp-content\/uploads\/2024\/05\/Coaching-Assessment-Tools-4-e1716349407364-1024x592.jpg","type":"","width":"","height":""}],"author":"Andrew Parker","twitter_card":"summary_large_image","twitter_creator":"@LeadershipCir","twitter_site":"@LeadershipCir","twitter_misc":{"Written by":"Leadership Circle","Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leadershipcircle.com\/pt-br\/blog\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\/#article","isPartOf":{"@id":"https:\/\/leadershipcircle.com\/pt-br\/blog\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\/"},"author":{"name":"Andrew Parker","@id":"https:\/\/leadershipcircle.com\/pt-br\/#\/schema\/person\/bae433ccd0703f445e1fc51812ccbc0b"},"headline":"As 15 principais ferramentas de avalia\u00e7\u00e3o de coaching para impulsionar o sucesso do cliente","datePublished":"2025-03-14T17:11:59+00:00","dateModified":"2025-07-02T14:20:36+00:00","mainEntityOfPage":{"@id":"https:\/\/leadershipcircle.com\/pt-br\/blog\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\/"},"wordCount":10829,"publisher":{"@id":"https:\/\/leadershipcircle.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/leadershipcircle.com\/pt-br\/blog\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\/#primaryimage"},"thumbnailUrl":"https:\/\/leadershipcircle.com\/wp-content\/uploads\/2024\/05\/Coaching-Assessment-Tools-4-e1716349407364.jpg","articleSection":["Coaches"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/leadershipcircle.com\/pt-br\/blog\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\/","url":"https:\/\/leadershipcircle.com\/pt-br\/blog\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\/","name":"As 15 principais ferramentas de avalia\u00e7\u00e3o de coaching para impulsionar o sucesso do cliente - Leadership Circle\u00ae","isPartOf":{"@id":"https:\/\/leadershipcircle.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leadershipcircle.com\/pt-br\/blog\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\/#primaryimage"},"image":{"@id":"https:\/\/leadershipcircle.com\/pt-br\/blog\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\/#primaryimage"},"thumbnailUrl":"https:\/\/leadershipcircle.com\/wp-content\/uploads\/2024\/05\/Coaching-Assessment-Tools-4-e1716349407364.jpg","datePublished":"2025-03-14T17:11:59+00:00","dateModified":"2025-07-02T14:20:36+00:00","description":"Explore 15 das ferramentas de avalia\u00e7\u00e3o de coaching mais prestigiadas e eficazes para acelerar o crescimento dos clientes e ampliar o seu impacto como coach.","breadcrumb":{"@id":"https:\/\/leadershipcircle.com\/pt-br\/blog\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leadershipcircle.com\/pt-br\/blog\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/leadershipcircle.com\/pt-br\/blog\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\/#primaryimage","url":"https:\/\/leadershipcircle.com\/wp-content\/uploads\/2024\/05\/Coaching-Assessment-Tools-4-e1716349407364.jpg","contentUrl":"https:\/\/leadershipcircle.com\/wp-content\/uploads\/2024\/05\/Coaching-Assessment-Tools-4-e1716349407364.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/leadershipcircle.com\/pt-br\/blog\/as-15-principais-ferramentas-de-avaliacao-de-coaching-para-impulsionar-o-sucesso-do-cliente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leadershipcircle.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"As 15 principais ferramentas de avalia\u00e7\u00e3o de coaching para impulsionar o sucesso do cliente"}]},{"@type":"WebSite","@id":"https:\/\/leadershipcircle.com\/pt-br\/#website","url":"https:\/\/leadershipcircle.com\/pt-br\/","name":"Leadership Circle","description":"The New Standard For Leadership Development","publisher":{"@id":"https:\/\/leadershipcircle.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leadershipcircle.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/leadershipcircle.com\/pt-br\/#organization","name":"The Leadership Circle","url":"https:\/\/leadershipcircle.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/leadershipcircle.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/leadershipcircle.com\/wp-content\/uploads\/2023\/02\/Leadership-Circle-Logo-2021_sq-color.png","contentUrl":"https:\/\/leadershipcircle.com\/wp-content\/uploads\/2023\/02\/Leadership-Circle-Logo-2021_sq-color.png","width":593,"height":593,"caption":"The Leadership Circle"},"image":{"@id":"https:\/\/leadershipcircle.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TheLeadershipCircle\/","https:\/\/x.com\/LeadershipCir","https:\/\/www.linkedin.com\/company\/the-leadership-circle"]},{"@type":"Person","@id":"https:\/\/leadershipcircle.com\/pt-br\/#\/schema\/person\/bae433ccd0703f445e1fc51812ccbc0b","name":"Andrew Parker","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/986943e43b09848d0c818b13ed40e33996f738b649d8a7c7126aeeb11be2ac6f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/986943e43b09848d0c818b13ed40e33996f738b649d8a7c7126aeeb11be2ac6f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/986943e43b09848d0c818b13ed40e33996f738b649d8a7c7126aeeb11be2ac6f?s=96&d=mm&r=g","caption":"Andrew Parker"}}]}},"_links":{"self":[{"href":"https:\/\/leadershipcircle.com\/pt-br\/wp-json\/wp\/v2\/posts\/136087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leadershipcircle.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leadershipcircle.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leadershipcircle.com\/pt-br\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/leadershipcircle.com\/pt-br\/wp-json\/wp\/v2\/comments?post=136087"}],"version-history":[{"count":0,"href":"https:\/\/leadershipcircle.com\/pt-br\/wp-json\/wp\/v2\/posts\/136087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leadershipcircle.com\/pt-br\/wp-json\/wp\/v2\/media\/119070"}],"wp:attachment":[{"href":"https:\/\/leadershipcircle.com\/pt-br\/wp-json\/wp\/v2\/media?parent=136087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leadershipcircle.com\/pt-br\/wp-json\/wp\/v2\/categories?post=136087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leadershipcircle.com\/pt-br\/wp-json\/wp\/v2\/tags?post=136087"},{"taxonomy":"wf_post_folders","embeddable":true,"href":"https:\/\/leadershipcircle.com\/pt-br\/wp-json\/wp\/v2\/wf_post_folders?post=136087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}